{"id":4779,"date":"2025-03-03T22:42:14","date_gmt":"2025-03-03T21:42:14","guid":{"rendered":"https:\/\/lima-sprachschule.de\/dev\/?post_type=product&#038;p=4779"},"modified":"2025-03-03T23:54:42","modified_gmt":"2025-03-03T22:54:42","slug":"englischkurs-online-2-mal-pro-woche","status":"publish","type":"product","link":"https:\/\/lima-sprachschule.de\/it\/kurs\/englischkurs-online-2-mal-pro-woche\/","title":{"rendered":"Englischkurs Online: 2 mal pro Woche"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4779\" class=\"elementor elementor-4779\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3702480e e-flex e-con-boxed e-con e-parent\" data-id=\"3702480e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-772fe149 elementor-widget elementor-widget-heading\" data-id=\"772fe149\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Englischkurs Online: 2 mal pro Woche - Dein individueller Weg zum Erfolg!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72337cf4 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72337cf4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-41121b2\" data-id=\"41121b2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e804eb8 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"e804eb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-calendar-alt\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M148 288h-40c-6.6 0-12-5.4-12-12v-40c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12zm108-12v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 96v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm192 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96-260v352c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V112c0-26.5 21.5-48 48-48h48V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h128V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h48c26.5 0 48 21.5 48 48zm-48 346V160H48v298c0 3.3 2.7 6 6 6h340c3.3 0 6-2.7 6-6z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tUnterrichtstage\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDienstag und Donnerstag\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-455735aa\" data-id=\"455735aa\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78daed45 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"78daed45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-play-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm115.7 272l-176 101c-15.8 8.8-35.7-2.5-35.7-21V152c0-18.4 19.8-29.8 35.7-21l176 107c16.4 9.2 16.4 32.9 0 42z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tKursdauer\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDer Kurs beginnt am zweiten Dienstag jedes Monats.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-63ff053d\" data-id=\"63ff053d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ea8fa24 elementor-widget__width-initial elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"3ea8fa24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-clock\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm0 448c-110.5 0-200-89.5-200-200S145.5 56 256 56s200 89.5 200 200-89.5 200-200 200zm61.8-104.4l-84.9-61.7c-3.1-2.3-4.9-5.9-4.9-9.7V116c0-6.6 5.4-12 12-12h32c6.6 0 12 5.4 12 12v141.7l66.8 48.6c5.4 3.9 6.5 11.4 2.6 16.8L334.6 349c-3.9 5.3-11.4 6.5-16.8 2.6z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tStartzeit (ab)\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t18:30 | 20:00\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-17706de9 e-flex e-con-boxed e-con e-parent\" data-id=\"17706de9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-58f47e8b elementor-widget elementor-widget-heading\" data-id=\"58f47e8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Flexibilit\u00e4t bei der Kursdauer<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23be7a3b elementor-widget elementor-widget-text-editor\" data-id=\"23be7a3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Dauer des Kurses und die Anzahl der Unterrichtsstunden variieren je nach Teilnehmerzahl. In der Regel finden die Kurse mit 4 Teilnehmern statt. Bei weniger Teilnehmern reduzieren wir die Unterrichtsstunden und passen die Kursdauer entsprechend an. So garantieren wir dir ein optimales Lernerlebnis in kleinen Gruppen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a51d69 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a51d69\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-28a4c310\" data-id=\"28a4c310\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4959ae2c elementor-widget elementor-widget-text-editor\" data-id=\"4959ae2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-sourcepos=\"6:1-6:77\"><strong>Lerne Englisch in deinem Rhythmus &#8211; gemeinsam mit der Lima Sprachschule!<\/strong><\/p><p data-sourcepos=\"8:1-8:273\">Du m\u00f6chtest Englisch lernen oder deine Kenntnisse verbessern, aber dein Alltag l\u00e4sst dir wenig Zeit f\u00fcr intensive Kurse? Kein Problem! Unser Online-Englischkurs mit zwei Sitzungen pro Woche ist die ideale L\u00f6sung f\u00fcr alle, die <strong>flexibel und effektiv<\/strong> lernen m\u00f6chten.<\/p><p data-sourcepos=\"11:1-11:54\"><strong>F\u00fchle dich wie zu Hause bei der Lima Sprachschule:<\/strong><\/p><p data-sourcepos=\"13:1-13:221\">Wir sind mehr als nur eine Sprachschule &#8211; <strong>wir sind eine Familie, die dich auf deiner Sprachreise begleitet.<\/strong> In unserer <strong>warmen und einladenden Atmosph\u00e4re<\/strong> wirst du dich wohlf\u00fchlen und mit Freude lernen.<\/p><p data-sourcepos=\"16:1-16:67\"><strong>Was macht unseren Kurs &#8220;Englisch 2 mal pro Woche&#8221; so besonders?<\/strong><\/p><ul data-sourcepos=\"18:1-26:0\"><li data-sourcepos=\"18:1-18:219\"><strong>Kontinuierliches Lernen:<\/strong> Zwei Unterrichtsstunden pro Woche (Dienstag und Donnerstag) erm\u00f6glichen es dir, regelm\u00e4\u00dfig am Ball zu bleiben und deine Englischkenntnisse kontinuierlich zu verbessern.<\/li><li data-sourcepos=\"19:1-19:177\"><strong>Moodle-Plattform:<\/strong> \u00dcbe t\u00e4glich mit interaktiven \u00dcbungen, zus\u00e4tzlichen Ressourcen und individuellem Feedback. Das Lernen h\u00f6rt nicht nach dem Unterricht auf!<\/li><li data-sourcepos=\"20:1-20:158\"><strong>Exklusive Materialien auf Spotify:<\/strong> Tauche mit unseren Podcasts und H\u00f6r\u00fcbungen in die Sprache ein \u2013 perfekt f\u00fcr unterwegs oder nebenbei!<\/li><li data-sourcepos=\"21:1-21:140\"><strong>Engagierte Lehrer:<\/strong> Lerne von unseren qualifizierten und motivierten Lehrern, die dir mit Rat und Tat zur Seite stehen.<\/li><li data-sourcepos=\"22:1-22:143\"><strong>Kleine Gruppen:<\/strong> Maximal 6 Teilnehmer pro Gruppe gew\u00e4hrleisten pers\u00f6nliche Aufmerksamkeit und eine interaktive Lernatmosph\u00e4re.<\/li><li data-sourcepos=\"23:1-23:140\"><strong>Kontinuierliche Unterst\u00fctzung:<\/strong> Stelle Fragen und erhalte Feedback jederzeit \u00fcber unsere WhatsApp-Gruppe mit deinem Lehrer.<\/li><li data-sourcepos=\"24:1-26:0\"><strong>Kreative Materialien:<\/strong> Wir verwenden eine Vielzahl von Methoden und Materialien, um den Unterricht lebendig und abwechslungsreich zu gestalten.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46b92bf1 elementor-widget elementor-widget-text-editor\" data-id=\"46b92bf1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 data-sourcepos=\"27:1-27:26\"><strong>Warum Englisch lernen?<\/strong><\/h3><p data-sourcepos=\"29:1-29:89\">Englisch ist die Weltsprache Nummer 1 und er\u00f6ffnet dir unz\u00e4hlige M\u00f6glichkeiten:<\/p><ul><li style=\"list-style-type: none;\"><ul><li style=\"list-style-type: none;\"><ul data-sourcepos=\"31:1-36:0\"><li data-sourcepos=\"31:1-31:196\"><strong>Reise die Welt:<\/strong> Bestelle in New York einen Kaffee, unterhalte dich in London mit den Einheimischen oder erkunde den australischen Outback \u2013 mit Englisch kein Problem!<\/li><li data-sourcepos=\"32:1-32:137\"><strong>Boost f\u00fcr deine Karriere:<\/strong> Verbessere deine Jobaussichten und sicher dir deinen Traumjob mit guten Englischkenntnissen.<\/li><li data-sourcepos=\"33:1-33:126\"><strong>Filme und Serien im Original:<\/strong> Genie\u00dfe deine Lieblingsfilme und -serien endlich ohne nervige Synchronisation.<\/li><li data-sourcepos=\"34:1-36:0\"><strong>Pers\u00f6nliches Wachstum:<\/strong> Erweitere deinen Horizont und \u00f6ffne dich neuen Kulturen und Erfahrungen.<\/li><\/ul><\/li><\/ul><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28d6496 elementor-widget elementor-widget-text-editor\" data-id=\"28d6496\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 data-sourcepos=\"37:1-37:37\"><strong>F\u00fcr wen ist dieser Kurs geeignet?<\/strong><\/h3><p data-sourcepos=\"39:1-39:40\">Dieser Kurs ist ideal f\u00fcr dich, wenn du:<\/p><ul><li style=\"list-style-type: none;\"><ul data-sourcepos=\"41:1-47:0\"><li data-sourcepos=\"41:1-41:148\"><strong>Regelm\u00e4\u00dfig lernen m\u00f6chtest:<\/strong> Zwei Sitzungen pro Woche helfen dir, am Ball zu bleiben und kontinuierlich Fortschritte zu machen.<\/li><li data-sourcepos=\"42:1-42:152\"><strong>Zeit zum \u00dcben brauchst:<\/strong> Zwischen den Unterrichtseinheiten hast du gen\u00fcgend Zeit, um das Gelernte zu wiederholen und zu vertiefen.<\/li><li data-sourcepos=\"43:1-43:151\"><strong>Flexibilit\u00e4t sch\u00e4tzt:<\/strong> Unser Online-Format erm\u00f6glicht es dir, von \u00fcberall aus zu lernen und den Kurs an deinen Alltag anzupassen.<\/li><li data-sourcepos=\"44:1-44:130\"><strong>In kleinen Gruppen lernen m\u00f6chtest:<\/strong> Profitiere von individueller Betreuung und einer pers\u00f6nlichen Lernatmosph\u00e4re.<\/li><li data-sourcepos=\"45:1-47:0\"><strong>Englisch f\u00fcr den Alltag, den Beruf oder die Freizeit lernen m\u00f6chtest:<\/strong> Egal, welche Ziele du verfolgst \u2013 mit unserem Kurs kommst du ihnen n\u00e4her.<\/li><\/ul><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be87d07 elementor-widget elementor-widget-text-editor\" data-id=\"be87d07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Lerne interaktiv und effektiv &#8211; mit unseren Top-Ressourcen<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42d70c9e elementor-widget elementor-widget-text-editor\" data-id=\"42d70c9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Live-Unterricht: Interaktiver Online-Unterricht mit erfahrenen Lehrern \u00fcber Microsoft Teams. Kein Microsoft-Konto erforderlich! Wir senden dir einen Link, mit dem du direkt am Unterricht teilnehmen kannst.<\/li><li>Dynamische \u00dcbungen: Vielf\u00e4ltige \u00dcbungen und Spiele zum interaktiven Lernen mit Wordwall und Kahoot.<\/li><li>Exklusives Material: Zus\u00e4tzliches Material zum Arbeitsbuch und Power Point Pr\u00e4sentationen.<\/li><li>E-Learning-Plattform: <a href=\"https:\/\/www.google.com\/search?q=https:\/\/moodle.lima-sprachschule.de&amp;authuser=1\">moodle.lima-sprachschule.de<\/a> mit zus\u00e4tzlichen \u00dcbungen und Tests.<\/li><li>Spotify: Podcasts mit praktischen \u00dcbungen zur Verbesserung der Aussprache.<\/li><li>Privat Chat: Exklusiver Kontakt zu deinem Lehrer, um Fragen zu kl\u00e4ren.<\/li><\/ul><p>Wir entwickeln uns st\u00e4ndig weiter!<\/p><p>Dein Lernerfolg ist unsere Motivation! Wir entwickeln stetig neue \u00dcbungen und Materialien, um auf die individuellen Bed\u00fcrfnisse unserer Sch\u00fcler einzugehen. So garantieren wir dir ein abwechslungsreiches und spannendes Lernerlebnis!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-504434a elementor-widget elementor-widget-text-editor\" data-id=\"504434a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 data-sourcepos=\"63:1-63:16\"><strong>Kursdetails:<\/strong><\/h3><ul data-sourcepos=\"65:1-71:0\"><li data-sourcepos=\"68:1-68:42\"><ul data-sourcepos=\"42:1-51:0\"><li data-sourcepos=\"42:1-42:41\"><p data-sourcepos=\"42:3-42:41\"><strong>Kurstage:<\/strong> Dienstag &amp; Donnerstag<\/p><\/li><li data-sourcepos=\"43:1-43:42\"><p data-sourcepos=\"43:3-43:42\"><strong>Kursbeginn:<\/strong> 18:30 Uhr oder 20:00 Uhr<\/p><\/li><li data-sourcepos=\"44:1-44:68\"><p data-sourcepos=\"44:3-44:68\"><strong>Startdaten:<\/strong> Der Kurs beginnt am zweiten Dienstag jedes Monats.<\/p><\/li><li data-sourcepos=\"45:1-51:0\"><p data-sourcepos=\"45:3-45:55\"><strong>Kursdauer:<\/strong> 8 Wochen (kann variieren, siehe unten)<\/p><ul data-sourcepos=\"47:5-51:0\"><li data-sourcepos=\"47:5-47:48\">32 Unterrichtsstunden (bei 4+ Teilnehmern)<\/li><li data-sourcepos=\"48:5-48:67\">28 Unterrichtsstunden (bei 3 Teilnehmern, Kursdauer 7 Wochen)<\/li><li data-sourcepos=\"49:5-49:67\">24 Unterrichtsstunden (bei 2 Teilnehmern, Kursdauer 6 Wochen)<\/li><li data-sourcepos=\"50:5-51:0\">16 Unterrichtsstunden (bei 1 Teilnehmer, Kursdauer 4 Wochen)<\/li><\/ul><\/li><\/ul><p data-sourcepos=\"52:1-52:15\"><strong>Preis:<\/strong> 420\u20ac<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-38c5670d\" data-id=\"38c5670d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-640caf20 elementor-widget elementor-widget-image\" data-id=\"640caf20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/sprachen-lernen-bei-der-lima-sprachschule-in-deutschland-34.png\" class=\"attachment-full size-full wp-image-4380\" alt=\"\" srcset=\"https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/sprachen-lernen-bei-der-lima-sprachschule-in-deutschland-34.png 600w, https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/sprachen-lernen-bei-der-lima-sprachschule-in-deutschland-34-300x300.png 300w, https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/sprachen-lernen-bei-der-lima-sprachschule-in-deutschland-34-100x100.png 100w, https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/sprachen-lernen-bei-der-lima-sprachschule-in-deutschland-34-400x400.png 400w, https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/sprachen-lernen-bei-der-lima-sprachschule-in-deutschland-34-150x150.png 150w, https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/sprachen-lernen-bei-der-lima-sprachschule-in-deutschland-34-1x1.png 1w, https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/sprachen-lernen-bei-der-lima-sprachschule-in-deutschland-34-10x10.png 10w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48d9939 elementor-widget elementor-widget-et-general-tabs\" data-id=\"48d9939\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"et-general-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div id=\"et-advance-tabs-48d9939\" class=\"et-advance-tabs et-tabs-horizontal  horizontal-style-1 responsive-vertical-layout\" data-tabid=\"48d9939\">\n            <div class=\"et-tabs-nav\">\n                <ul >\n\t\t\t\t\t                        <li class=\"inactive et-tab-nav\"\n                            >\n                            \t\t\t\t\t\t\t\t                        \t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <span class=\"et-tab-title\">\n    \t\t\t\t\t\t\t\tNiveaustufen im Englischkurs    \t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t                        <\/li>\n\t\t\t\t\t                        <li class=\"inactive et-tab-nav\"\n                            >\n                            \t\t\t\t\t\t\t\t                        \t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <span class=\"et-tab-title\">\n    \t\t\t\t\t\t\t\tWas mache ich, wenn ich au\u00dferhalb der Unterrichtszeiten Fragen habe?    \t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t                        <\/li>\n\t\t\t\t\t                        <li class=\"inactive et-tab-nav\"\n                            >\n                            \t\t\t\t\t\t\t\t                        \t\t\t\t\t\t\t\t\t\t\t\t\t\t                                <span class=\"et-tab-title\">\n    \t\t\t\t\t\t\t\tWarum sollten Sie uns w\u00e4hlen?    \t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t                        <\/li>\n\t\t\t\t\t                <\/ul>\n                            <\/div>\n            <div class=\"et-tabs-content\">\n\t\t\t\t                    <div class=\"clearfix inactive\">\n\t\t\t\t\t\t<h3><strong>Der Gemeinsame Europ\u00e4ische Referenzrahmen (GER)<\/strong><\/h3><p>Unsere Englischkurse sind nach den Niveaustufen des Gemeinsamen Europ\u00e4ischen Referenzrahmens f\u00fcr Sprachen (GER) aufgebaut. Der GER ist ein internationaler Standard, der die Sprachkenntnisse in sechs Stufen einteilt:<\/p><ul><li><strong>A1 und A2:<\/strong> Elementare Sprachverwendung<\/li><li><strong>B1 und B2:<\/strong> Selbstst\u00e4ndige Sprachverwendung<\/li><li><strong style=\"color: inherit; font-family: inherit; font-size: inherit; background-color: var(--et_container-bg-color,transparent);\">C1 und C2:<\/strong><span style=\"color: inherit; font-family: inherit; font-size: inherit; font-weight: var( --e-global-typography-text-font-weight ); background-color: var(--et_container-bg-color,transparent);\"> Kompetente Sprachverwendung<\/span><\/li><\/ul><p>Jede Stufe ist weiter in zwei Unterstufen unterteilt (z.B. A1.1, A1.2, A2.1, A2.2, etc.).<span style=\"color: inherit; font-family: inherit; font-size: inherit; font-weight: var( --e-global-typography-text-font-weight ); background-color: var(--et_container-bg-color,transparent);\"><br \/><a href=\"https:\/\/www.europaeischer-referenzrahmen.de\/index.php\">Mehr \u00fcber den GER erfahren<\/a><br \/><\/span><\/p><h4><strong>Warum ist es wichtig, mit dem GER zu lernen?<\/strong><\/h4><ul><li><strong>International anerkannt:<\/strong> Der GER ist ein internationaler Standard, der von vielen Institutionen und Arbeitgebern anerkannt wird.<\/li><li><strong>Klare Lernziele:<\/strong> Der GER definiert klare Lernziele f\u00fcr jede Niveaustufe, sodass du genau wei\u00dft, was du auf jedem Niveau lernen wirst.<\/li><li><strong>Transparenz:<\/strong> Du kannst deine Sprachkenntnisse eindeutig einstufen und mit anderen vergleichen.<\/li><li><strong>Effektives Lernen:<\/strong> Unsere Kurse sind optimal auf die Lernziele des GER abgestimmt, sodass du dein Sprachniveau systematisch und effektiv verbessern kannst.<\/li><\/ul>                    <\/div>\n\t\t\t\t                    <div class=\"clearfix inactive\">\n\t\t\t\t\t\t<p>Kein Problem! Du kannst jederzeit deinen Lehrer \u00fcber unseren privaten Chat kontaktieren und ihm deine Fragen stellen. Au\u00dferdem steht dir unsere Moodle-Plattform mit zus\u00e4tzlichen \u00dcbungen und Materialien zur Verf\u00fcgung, um dein Spanisch auch au\u00dferhalb des Unterrichts zu trainieren.<\/p>                    <\/div>\n\t\t\t\t                    <div class=\"clearfix inactive\">\n\t\t\t\t\t\t<p data-sourcepos=\"20:8-20:100\">Wir bieten dir einen hochwertigen und effektiven Englischkurs mit vielen Vorteilen:<\/p><ul data-sourcepos=\"21:8-27:31\"><li data-sourcepos=\"22:8-22:112\"><strong>Dynamische und innovative Methodik:<\/strong> Unser Unterricht ist abwechslungsreich und motivierend.<\/li><li data-sourcepos=\"23:8-23:114\"><strong>Kleine Gruppen:<\/strong> Profitiere von individueller Betreuung und einer pers\u00f6nlichen Lernatmosph\u00e4re.<\/li><li data-sourcepos=\"24:8-24:69\"><strong>Flexibilit\u00e4t:<\/strong> Lerne online, wann und wo du willst.<\/li><li data-sourcepos=\"25:8-25:138\"><strong>Zus\u00e4tzliche Lernressourcen:<\/strong> Vertiefe dein Wissen mit unserer Moodle-Plattform, Wordwall, Kahoot und anderen Tools.<\/li><li data-sourcepos=\"26:8-26:96\"><strong>Garantierter Kursstart:<\/strong> Auch mit wenigen Teilnehmern findet der Kurs statt!<\/li><li data-sourcepos=\"27:8-27:31\"><strong>Und vieles mehr!<\/strong><\/li><\/ul>                    <\/div>\n\t\t\t\t            <\/div>\n        <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e976ade elementor-widget elementor-widget-image\" data-id=\"4e976ade\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/niveustufen.png\" class=\"attachment-large size-large wp-image-3587\" alt=\"\" srcset=\"https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/niveustufen.png 800w, https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/niveustufen-400x300.png 400w, https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/niveustufen-300x225.png 300w, https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/niveustufen-768x576.png 768w, https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/niveustufen-1x1.png 1w, https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/niveustufen-10x8.png 10w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-377fc631 elementor-widget elementor-widget-text-editor\" data-id=\"377fc631\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-sourcepos=\"55:1-55:22\"><span style=\"color: #ff0000;\"><strong>Wichtige Hinweise:<\/strong><\/span><\/p><ul data-sourcepos=\"57:1-60:0\"><li data-sourcepos=\"57:1-57:170\"><strong>Vorkenntnisse:<\/strong> Um optimal vom Kurs zu profitieren, solltest du bereits Grundkenntnisse in einer anderen Sprache haben und mit grammatischen Begriffen vertraut sein.<\/li><li data-sourcepos=\"58:1-60:0\"><strong>Einstufungstest:<\/strong> Es ist wichtig, dass du vor Kursbeginn unseren Online-Test machst, um dein Sprachniveau einzustufen.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30682459 elementor-widget elementor-widget-image\" data-id=\"30682459\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/lima-sprachschule.de\/kostenloser-einstufungstest-online\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"200\" src=\"https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/3-2.png\" class=\"attachment-large size-large wp-image-11174\" alt=\"\" srcset=\"https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/3-2.png 800w, https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/3-2-400x100.png 400w, https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/3-2-300x75.png 300w, https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/3-2-768x192.png 768w, https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/3-2-1x1.png 1w, https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/3-2-10x3.png 10w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74ae444a elementor-widget elementor-widget-text-editor\" data-id=\"74ae444a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 data-sourcepos=\"45:1-45:79\">Dein Sprachkurs \u2013 garantiert!<\/h3><p data-sourcepos=\"47:1-47:410\">Warst du schon einmal in der Situation, dass dein Sprachkurs wegen zu geringer Teilnehmerzahl abgesagt wurde? Bei uns passiert dir das nicht! Wir starten den Kurs auch mit nur einem Teilnehmer! So kannst du deine Pl\u00e4ne verwirklichen und profitierst von einem fast privaten Kurs zum Gruppenpreis. Die Stundenzahl wird reduziert, aber du erh\u00e4ltst die volle Aufmerksamkeit des Lehrers und kannst so noch effektiver lernen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c22958d elementor-widget elementor-widget-text-editor\" data-id=\"6c22958d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 data-sourcepos=\"50:1-50:23\"><strong>Dein Einsatz z\u00e4hlt!<\/strong><\/h3><p data-sourcepos=\"52:1-52:356\">Der Erfolg dieses Kurses h\u00e4ngt nicht nur von unseren Lehrern und Materialien ab, sondern auch von deinem eigenen Engagement. Nutze die Zeit zwischen den Unterrichtseinheiten, um das Gelernte zu wiederholen und zu vertiefen. Auf unserer Moodle-Plattform findest du zus\u00e4tzliche \u00dcbungen und Materialien, die dich dabei unterst\u00fctzen.<\/p><p data-sourcepos=\"79:1-79:15\"><strong>Lehrb\u00fccher:<\/strong><\/p><p data-sourcepos=\"81:1-81:169\">Wir arbeiten mit renommierten Verlagen zusammen, um dir die besten Lehrb\u00fccher anzubieten. Informationen zum empfohlenen Lehrbuch erh\u00e4ltst du in der Best\u00e4tigungs-E-Mail.<\/p><h3 data-sourcepos=\"84:1-84:34\"><strong>Was ben\u00f6tigst du f\u00fcr den Kurs?<\/strong><\/h3><ul data-sourcepos=\"86:1-91:0\"><li data-sourcepos=\"86:1-86:54\">Einen Laptop oder ein Tablet mit Internetverbindung.<\/li><li data-sourcepos=\"87:1-87:26\">Das empfohlene Lehrbuch.<\/li><li data-sourcepos=\"88:1-88:96\">Grundlegende Materialien wie Papier, Buntstifte, Schere, etc. f\u00fcr die praktischen Aktivit\u00e4ten.<\/li><li data-sourcepos=\"89:1-91:0\">Einen Ordner, um deine Kursmaterialien zu organisieren.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4147f606 elementor-widget elementor-widget-image\" data-id=\"4147f606\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"200\" src=\"https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/qualitaet-seit-2018-lima-sprachschule.png\" class=\"attachment-full size-full wp-image-3588\" alt=\"\" srcset=\"https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/qualitaet-seit-2018-lima-sprachschule.png 800w, https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/qualitaet-seit-2018-lima-sprachschule-400x100.png 400w, https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/qualitaet-seit-2018-lima-sprachschule-300x75.png 300w, https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/qualitaet-seit-2018-lima-sprachschule-768x192.png 768w, https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/qualitaet-seit-2018-lima-sprachschule-1x1.png 1w, https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/qualitaet-seit-2018-lima-sprachschule-10x3.png 10w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c811756 elementor-widget elementor-widget-text-editor\" data-id=\"2c811756\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unsere erfahrenen Lehrer und unsere innovative Methodik haben seit 2018 in M\u00fcnchen zahlreiche Sch\u00fcler begeistert. \u00dcberzeuge dich selbst von unserer Qualit\u00e4t und starte deine Sprachreise mit der Lima Sprachschule!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-587083cf e-con-full e-flex e-con e-parent\" data-id=\"587083cf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-31f694da elementor-widget elementor-widget-text-editor\" data-id=\"31f694da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 data-sourcepos=\"92:1-92:27\"><strong>Worauf wartest du noch?<\/strong><\/h3><p data-sourcepos=\"94:1-94:122\">Melde dich jetzt zu unserem Englischkurs Online 2 mal pro Woche an und starte deine Sprachreise mit der Lima Sprachschule!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2f8c3b9d e-con-full e-flex e-con e-parent\" data-id=\"2f8c3b9d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a3813d7 elementor-widget elementor-widget-video\" data-id=\"a3813d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/jryimhkAzuk?si=7PQT2mvsXeIIZ5d7&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"> <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"default\" data-borlabs-cookie-content=\"PHNjcmlwdD4KKGZ1bmN0aW9uKCkgewogICAgbGV0IGQgPSBudWxsOwoKICAgIC8vIGlmIHdlIGFyZSBpbiBhIGxvb3AsIHdlIG5lZWQgdG8gc2VsZWN0IHRoZSBjb3JyZWN0IHZpZGVvIGVsZW1lbnQsIHNpbmNlIFdpZGdldCBJRCBvY2N1cnMgbXVsdGlwbGUgdGltZXMgb24gcGFnZQogICAgY29uc3QgZWxlbXNJbkxvb3AgPSBkb2N1bWVudC5xdWVyeVNlbGVjdG9yQWxsKCc6aXMoZGl2W2RhdGEtZWxlbWVudG9yLXR5cGU9Imxvb3AtaXRlbSJdLGRpdltkYXRhLWVsZW1lbnRvci10eXBlPSJqZXQtbGlzdGluZy1pdGVtcyJdKSBkaXYuZWxlbWVudG9yLWVsZW1lbnQtYTM4MTNkNycpOwogICAgaWYgKGVsZW1zSW5Mb29wLmxlbmd0aCA9PT0gMSkgewogICAgICAgIGQgPSBlbGVtc0luTG9vcFswXTsKICAgIH0gZWxzZSBpZiAoZWxlbXNJbkxvb3AubGVuZ3RoID4gMSkgewogICAgICAgIGlmICh0eXBlb2YgZG9jdW1lbnQuY3VycmVudFNjcmlwdCA9PT0gJ3VuZGVmaW5lZCcgfHwgZG9jdW1lbnQuY3VycmVudFNjcmlwdCA9PSBudWxsKSB7CiAgICAgICAgICAgIHJldHVybjsKICAgICAgICB9CiAgICAgICAgY29uc3QgdG1wVmlkZW9XaWRnZXQgPSBkb2N1bWVudC5jdXJyZW50U2NyaXB0LmNsb3Nlc3QoJ1tkYXRhLXdpZGdldF90eXBlPSJicmxic192aWRlby5kZWZhdWx0Il0nKTsKICAgICAgICBpZiAodG1wVmlkZW9XaWRnZXQpIHsKICAgICAgICAgICAgZCA9IHRtcFZpZGVvV2lkZ2V0OwogICAgICAgIH0KICAgIH0KCiAgICBpZiAoZCA9PSBudWxsKSB7CiAgICAgICAgZCA9IGRvY3VtZW50LnF1ZXJ5U2VsZWN0b3IoJ2Rpdi5lbGVtZW50b3ItZWxlbWVudC1hMzgxM2Q3Jyk7CiAgICB9CgogICAgaWYgKGQgPT0gbnVsbCkgewogICAgICAgIHJldHVybjsKICAgIH0KICAgIGQuZGF0YXNldC53aWRnZXRfdHlwZSA9IGQuZGF0YXNldC53aWRnZXRfdHlwZS5yZXBsYWNlKCdicmxic18nLCAnJyk7CiAgICBkLmRhdGFzZXQuYnJsYnNVbmJsb2NrZWQgPSAndHJ1ZSc7CgogICAgY29uc3QgaW50ZXJ2YWwgPSBzZXRJbnRlcnZhbCgoKSA9PiB7CiAgICAgICAgaWYgKHR5cGVvZiBlbGVtZW50b3JGcm9udGVuZCAhPT0gJ3VuZGVmaW5lZCcgJiYgdHlwZW9mIGVsZW1lbnRvckZyb250ZW5kLmhvb2tzICE9PSAndW5kZWZpbmVkJykgewogICAgICAgICAgICBjbGVhckludGVydmFsKGludGVydmFsKTsKICAgICAgICAgICAgZWxlbWVudG9yRnJvbnRlbmQuaG9va3MuZG9BY3Rpb24oJ2Zyb250ZW5kL2VsZW1lbnRfcmVhZHkvdmlkZW8uZGVmYXVsdCcsIGpRdWVyeShkKSwgalF1ZXJ5KQogICAgICAgIH0KICAgIH0sIDMwKQp9KSgpOwo8L3NjcmlwdD4=\"><div class=\"brlbs-cmpnt-cb-preset-a\"> <p class=\"brlbs-cmpnt-cb-description\">Stai visualizzando un contenuto segnaposto da <strong>Predefinito<\/strong>. Per accedere al contenuto effettivo, clicca sul pulsante sottostante. Si prega di notare che in questo modo si condividono i dati con provider di terze parti.<\/p> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Sblocca il contenuto<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: none\">Accetta il servizio richiesto e sblocca i contenuti<\/a> <\/div> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Ulteriori informazioni<\/a> <\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-34baffd0 e-con-full e-flex e-con e-parent\" data-id=\"34baffd0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-455066eb e-con-full e-flex e-con e-child\" data-id=\"455066eb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7579864c e-con-full e-flex e-con e-child\" data-id=\"7579864c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Englischkurs Online: 2 mal pro Woche &#8211; Dein individueller Weg zum Erfolg! Unterrichtstage Dienstag und Donnerstag Kursdauer Der Kurs beginnt am zweiten Dienstag jedes Monats&#8230;.<\/p>\n","protected":false},"featured_media":4753,"comment_status":"open","ping_status":"closed","template":"","meta":[],"etheme_brands":[],"product_brand":[],"product_cat":[469,444,445,446,447,457,254,448,449,450,451,452,453,523,108,278,275,266,465,443,442,458,454],"product_tag":[],"class_list":{"0":"post-4779","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-2x-pro-woche","7":"product_cat-a1-1","8":"product_cat-a1-2","9":"product_cat-a2-1","10":"product_cat-a2-2","11":"product_cat-abend","12":"product_cat-altersgruppe-deutsch","13":"product_cat-b1-1","14":"product_cat-b1-2","15":"product_cat-b2-1","16":"product_cat-b2-2","17":"product_cat-c1-1","18":"product_cat-c1-2","19":"product_cat-dienstag-und-donnerstag","20":"product_cat-englisch","21":"product_cat-erwachsene-18-jahre-altersgruppe-deutsch","22":"product_cat-jugendliche-13-17-jahre-altersgruppe-deutsch","23":"product_cat-kinder-8-12-jahre-altersgruppe-deutsch","24":"product_cat-kursart","25":"product_cat-niveau","26":"product_cat-sprachen","27":"product_cat-tage","28":"product_cat-zeitplan","30":"first","31":"instock","32":"shipping-taxable","33":"purchasable","34":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Englischkurs Online: 2 mal pro Woche - Lima Sprachschule<\/title>\n<meta name=\"description\" content=\"Spanischkurs online 2 mal pro WocheLerne Spanisch 2x\/Woche online! \ud83c\uddea\ud83c\uddf8 Flexibel, effektiv &amp; mit muttersprachlichen Lehrern. Moodle-Plattform &amp; mehr. Nur 420\u20ac! Jetzt anmelden!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lima-sprachschule.de\/it\/kurs\/englischkurs-online-2-mal-pro-woche\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Englischkurs Online: 2 mal pro Woche\" \/>\n<meta property=\"og:description\" content=\"Lerne Spanisch 2x\/Woche online! \ud83c\uddea\ud83c\uddf8 Flexibel, effektiv &amp; mit muttersprachlichen Lehrern. Moodle-Plattform &amp; mehr. Nur 420\u20ac! Jetzt anmelden!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lima-sprachschule.de\/it\/kurs\/englischkurs-online-2-mal-pro-woche\/\" \/>\n<meta property=\"og:site_name\" content=\"Lima Sprachschule\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LimaSprachschuleinMuenchen\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-03T22:54:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/03\/Englisch-2-mal-in-der-Woche.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@LimaSprachen\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lima-sprachschule.de\/it\/kurs\/englischkurs-online-2-mal-pro-woche\/\",\"url\":\"https:\/\/lima-sprachschule.de\/it\/kurs\/englischkurs-online-2-mal-pro-woche\/\",\"name\":\"Englischkurs Online: 2 mal pro Woche - Lima Sprachschule\",\"isPartOf\":{\"@id\":\"https:\/\/lima-sprachschule.de\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lima-sprachschule.de\/it\/kurs\/englischkurs-online-2-mal-pro-woche\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/lima-sprachschule.de\/it\/kurs\/englischkurs-online-2-mal-pro-woche\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/03\/Englisch-2-mal-in-der-Woche.png\",\"datePublished\":\"2025-03-03T21:42:14+00:00\",\"dateModified\":\"2025-03-03T22:54:42+00:00\",\"description\":\"Spanischkurs online 2 mal pro WocheLerne Spanisch 2x\/Woche online! \ud83c\uddea\ud83c\uddf8 Flexibel, effektiv & mit muttersprachlichen Lehrern. Moodle-Plattform & mehr. Nur 420\u20ac! Jetzt anmelden!\",\"breadcrumb\":{\"@id\":\"https:\/\/lima-sprachschule.de\/it\/kurs\/englischkurs-online-2-mal-pro-woche\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lima-sprachschule.de\/it\/kurs\/englischkurs-online-2-mal-pro-woche\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/lima-sprachschule.de\/it\/kurs\/englischkurs-online-2-mal-pro-woche\/#primaryimage\",\"url\":\"https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/03\/Englisch-2-mal-in-der-Woche.png\",\"contentUrl\":\"https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/03\/Englisch-2-mal-in-der-Woche.png\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lima-sprachschule.de\/it\/kurs\/englischkurs-online-2-mal-pro-woche\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/lima-sprachschule.de\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/lima-sprachschule.de\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Englischkurs Online: 2 mal pro Woche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lima-sprachschule.de\/it\/#website\",\"url\":\"https:\/\/lima-sprachschule.de\/it\/\",\"name\":\"Lima Sprachschule\",\"description\":\"Sprachen lernen kann einfach sein!\",\"publisher\":{\"@id\":\"https:\/\/lima-sprachschule.de\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lima-sprachschule.de\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lima-sprachschule.de\/it\/#organization\",\"name\":\"Lima Sprachschule\",\"alternateName\":\"LS\",\"url\":\"https:\/\/lima-sprachschule.de\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/lima-sprachschule.de\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/logo-color-300px.png\",\"contentUrl\":\"https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/logo-color-300px.png\",\"width\":300,\"height\":234,\"caption\":\"Lima Sprachschule\"},\"image\":{\"@id\":\"https:\/\/lima-sprachschule.de\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/LimaSprachschuleinMuenchen\",\"https:\/\/x.com\/LimaSprachen\",\"https:\/\/www.instagram.com\/limasprachschule\/\",\"https:\/\/www.youtube.com\/channel\/UCGtyhoDdjW70De5B1Urlz2g\",\"https:\/\/t.me\/LimaSprachschuleLS\",\"https:\/\/www.youtube.com\/@limasprachschule8844\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Englischkurs Online: 2 mal pro Woche - Lima Sprachschule","description":"Spanischkurs online 2 mal pro WocheLerne Spanisch 2x\/Woche online! \ud83c\uddea\ud83c\uddf8 Flexibel, effektiv & mit muttersprachlichen Lehrern. Moodle-Plattform & mehr. Nur 420\u20ac! Jetzt anmelden!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lima-sprachschule.de\/it\/kurs\/englischkurs-online-2-mal-pro-woche\/","og_locale":"it_IT","og_type":"article","og_title":"Englischkurs Online: 2 mal pro Woche","og_description":"Lerne Spanisch 2x\/Woche online! \ud83c\uddea\ud83c\uddf8 Flexibel, effektiv & mit muttersprachlichen Lehrern. Moodle-Plattform & mehr. Nur 420\u20ac! Jetzt anmelden!","og_url":"https:\/\/lima-sprachschule.de\/it\/kurs\/englischkurs-online-2-mal-pro-woche\/","og_site_name":"Lima Sprachschule","article_publisher":"https:\/\/www.facebook.com\/LimaSprachschuleinMuenchen","article_modified_time":"2025-03-03T22:54:42+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/03\/Englisch-2-mal-in-der-Woche.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@LimaSprachen","twitter_misc":{"Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lima-sprachschule.de\/it\/kurs\/englischkurs-online-2-mal-pro-woche\/","url":"https:\/\/lima-sprachschule.de\/it\/kurs\/englischkurs-online-2-mal-pro-woche\/","name":"Englischkurs Online: 2 mal pro Woche - Lima Sprachschule","isPartOf":{"@id":"https:\/\/lima-sprachschule.de\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lima-sprachschule.de\/it\/kurs\/englischkurs-online-2-mal-pro-woche\/#primaryimage"},"image":{"@id":"https:\/\/lima-sprachschule.de\/it\/kurs\/englischkurs-online-2-mal-pro-woche\/#primaryimage"},"thumbnailUrl":"https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/03\/Englisch-2-mal-in-der-Woche.png","datePublished":"2025-03-03T21:42:14+00:00","dateModified":"2025-03-03T22:54:42+00:00","description":"Spanischkurs online 2 mal pro WocheLerne Spanisch 2x\/Woche online! \ud83c\uddea\ud83c\uddf8 Flexibel, effektiv & mit muttersprachlichen Lehrern. Moodle-Plattform & mehr. Nur 420\u20ac! Jetzt anmelden!","breadcrumb":{"@id":"https:\/\/lima-sprachschule.de\/it\/kurs\/englischkurs-online-2-mal-pro-woche\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lima-sprachschule.de\/it\/kurs\/englischkurs-online-2-mal-pro-woche\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/lima-sprachschule.de\/it\/kurs\/englischkurs-online-2-mal-pro-woche\/#primaryimage","url":"https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/03\/Englisch-2-mal-in-der-Woche.png","contentUrl":"https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/03\/Englisch-2-mal-in-der-Woche.png","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/lima-sprachschule.de\/it\/kurs\/englischkurs-online-2-mal-pro-woche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/lima-sprachschule.de\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/lima-sprachschule.de\/shop\/"},{"@type":"ListItem","position":3,"name":"Englischkurs Online: 2 mal pro Woche"}]},{"@type":"WebSite","@id":"https:\/\/lima-sprachschule.de\/it\/#website","url":"https:\/\/lima-sprachschule.de\/it\/","name":"Lima Sprachschule","description":"Sprachen lernen kann einfach sein!","publisher":{"@id":"https:\/\/lima-sprachschule.de\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lima-sprachschule.de\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/lima-sprachschule.de\/it\/#organization","name":"Lima Sprachschule","alternateName":"LS","url":"https:\/\/lima-sprachschule.de\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/lima-sprachschule.de\/it\/#\/schema\/logo\/image\/","url":"https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/logo-color-300px.png","contentUrl":"https:\/\/lima-sprachschule.de\/wp-content\/uploads\/2025\/02\/logo-color-300px.png","width":300,"height":234,"caption":"Lima Sprachschule"},"image":{"@id":"https:\/\/lima-sprachschule.de\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LimaSprachschuleinMuenchen","https:\/\/x.com\/LimaSprachen","https:\/\/www.instagram.com\/limasprachschule\/","https:\/\/www.youtube.com\/channel\/UCGtyhoDdjW70De5B1Urlz2g","https:\/\/t.me\/LimaSprachschuleLS","https:\/\/www.youtube.com\/@limasprachschule8844"]}]}},"_links":{"self":[{"href":"https:\/\/lima-sprachschule.de\/it\/wp-json\/wp\/v2\/product\/4779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lima-sprachschule.de\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lima-sprachschule.de\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lima-sprachschule.de\/it\/wp-json\/wp\/v2\/comments?post=4779"}],"version-history":[{"count":5,"href":"https:\/\/lima-sprachschule.de\/it\/wp-json\/wp\/v2\/product\/4779\/revisions"}],"predecessor-version":[{"id":4840,"href":"https:\/\/lima-sprachschule.de\/it\/wp-json\/wp\/v2\/product\/4779\/revisions\/4840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lima-sprachschule.de\/it\/wp-json\/wp\/v2\/media\/4753"}],"wp:attachment":[{"href":"https:\/\/lima-sprachschule.de\/it\/wp-json\/wp\/v2\/media?parent=4779"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/lima-sprachschule.de\/it\/wp-json\/wp\/v2\/etheme_brands?post=4779"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lima-sprachschule.de\/it\/wp-json\/wp\/v2\/product_brand?post=4779"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lima-sprachschule.de\/it\/wp-json\/wp\/v2\/product_cat?post=4779"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lima-sprachschule.de\/it\/wp-json\/wp\/v2\/product_tag?post=4779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}